{"id":5402,"date":"2026-02-02T17:36:16","date_gmt":"2026-02-02T20:36:16","guid":{"rendered":"https:\/\/ppgusrn.cnat.ifrn.edu.br\/?p=5402"},"modified":"2026-02-02T17:36:16","modified_gmt":"2026-02-02T20:36:16","slug":"retificacao-do-edital-no-01-2026-credenciamento-docente-no-ppgusrn","status":"publish","type":"post","link":"https:\/\/ppgusrn.cnat.ifrn.edu.br\/index.php\/2026\/02\/02\/retificacao-do-edital-no-01-2026-credenciamento-docente-no-ppgusrn\/","title":{"rendered":"Retifica\u00e7\u00e3o do Edital n\u00ba 01\/2026 \u2013 Credenciamento Docente no PPgUSRN"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\">\n<p>O PPgUSRN do IFRN torna p\u00fablica a retifica\u00e7\u00e3o do Edital n\u00ba 01\/2026, referente ao processo de credenciamento docente ao Programa.<\/p>\n\n\n\n<p>A retifica\u00e7\u00e3o tem por finalidade atualizar o cronograma de execu\u00e7\u00e3o do edital originalmente publicado, incluindo. Recomenda-se que todos(as) os(as) interessados(as) leiam integralmente o documento de retifica\u00e7\u00e3o, uma vez que ele passa a integrar o Edital n\u00ba 01\/2026 para todos os fins.<\/p>\n\n\n\n<p><a href=\"https:\/\/ppgusrn.cnat.ifrn.edu.br\/wp-content\/uploads\/2026\/02\/RETIFICACAO-DO-EDITAL-01.2026_PPGUSRN.pdf\">Retifica\u00e7\u00e3o do Edital n\u00ba 01\/2026 \u2013 Credenciamento Docente no PPgUSRN<\/a><\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O PPgUSRN do IFRN torna p\u00fablica a retifica\u00e7\u00e3o do Edital n\u00ba 01\/2026, referente ao processo de credenciamento docente ao Programa. A retifica\u00e7\u00e3o tem por finalidade atualizar o cronograma de execu\u00e7\u00e3o&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/ppgusrn.cnat.ifrn.edu.br\/index.php\/wp-json\/wp\/v2\/posts\/5402"}],"collection":[{"href":"https:\/\/ppgusrn.cnat.ifrn.edu.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ppgusrn.cnat.ifrn.edu.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ppgusrn.cnat.ifrn.edu.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ppgusrn.cnat.ifrn.edu.br\/index.php\/wp-json\/wp\/v2\/comments?post=5402"}],"version-history":[{"count":1,"href":"https:\/\/ppgusrn.cnat.ifrn.edu.br\/index.php\/wp-json\/wp\/v2\/posts\/5402\/revisions"}],"predecessor-version":[{"id":5403,"href":"https:\/\/ppgusrn.cnat.ifrn.edu.br\/index.php\/wp-json\/wp\/v2\/posts\/5402\/revisions\/5403"}],"wp:attachment":[{"href":"https:\/\/ppgusrn.cnat.ifrn.edu.br\/index.php\/wp-json\/wp\/v2\/media?parent=5402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ppgusrn.cnat.ifrn.edu.br\/index.php\/wp-json\/wp\/v2\/categories?post=5402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ppgusrn.cnat.ifrn.edu.br\/index.php\/wp-json\/wp\/v2\/tags?post=5402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}